{"id":1490,"date":"2023-03-13T11:46:37","date_gmt":"2023-03-13T11:46:37","guid":{"rendered":"https:\/\/whatmkt.com\/faq-items\/que-es-un-marketplace\/"},"modified":"2023-03-14T17:23:27","modified_gmt":"2023-03-14T17:23:27","slug":"que-es-un-marketplace","status":"publish","type":"avada_faq","link":"https:\/\/whatmkt.com\/ca\/faq-items\/que-es-un-marketplace\/","title":{"rendered":"Qu\u00e8 \u00e9s un marketplace?"},"content":{"rendered":"<p><strong>Un marketplace<\/strong> (o mercat en l\u00ednia) \u00e9s una plataforma digital que reuneix diferents venedors i compradors en un sol lloc per a realitzar transaccions comercials. Els marketplaces s\u00f3n similars als centres comercials f\u00edsics, on m\u00faltiples botigues es troben en un sol lloc i els consumidors poden comparar i comprar productes de diferents venedors.<\/p>\n<p>En un marketplace en l\u00ednia, els venedors poden oferir els seus productes o serveis en un sol lloc, i els compradors poden buscar i comparar diferents opcions de compra en la mateixa plataforma. Alguns exemples populars de marketplaces en l\u00ednia inclouen Amazon, eBay, Airbnb i Uber.<\/p>\n<p>En un marketplace, els venedors poden aprofitar la base de clients existent i la infraestructura de la plataforma per a promocionar els seus productes i arribar a nous clients. A m\u00e9s, els marketplaces solen oferir eines per a gestionar les vendes, l&#8217;inventari i l&#8217;enviament dels productes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un marketplace (o mercat en l\u00ednia) \u00e9s una plataforma digital  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"footnotes":""},"faq_category":[38],"class_list":["post-1490","avada_faq","type-avada_faq","status-publish","format-standard","hentry","faq_category-transformacio-digital"],"_links":{"self":[{"href":"https:\/\/whatmkt.com\/ca\/wp-json\/wp\/v2\/avada_faq\/1490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whatmkt.com\/ca\/wp-json\/wp\/v2\/avada_faq"}],"about":[{"href":"https:\/\/whatmkt.com\/ca\/wp-json\/wp\/v2\/types\/avada_faq"}],"author":[{"embeddable":true,"href":"https:\/\/whatmkt.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/whatmkt.com\/ca\/wp-json\/wp\/v2\/comments?post=1490"}],"version-history":[{"count":2,"href":"https:\/\/whatmkt.com\/ca\/wp-json\/wp\/v2\/avada_faq\/1490\/revisions"}],"predecessor-version":[{"id":1509,"href":"https:\/\/whatmkt.com\/ca\/wp-json\/wp\/v2\/avada_faq\/1490\/revisions\/1509"}],"wp:attachment":[{"href":"https:\/\/whatmkt.com\/ca\/wp-json\/wp\/v2\/media?parent=1490"}],"wp:term":[{"taxonomy":"faq_category","embeddable":true,"href":"https:\/\/whatmkt.com\/ca\/wp-json\/wp\/v2\/faq_category?post=1490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}